{"id":24039,"date":"2026-04-08T14:26:41","date_gmt":"2026-04-08T17:26:41","guid":{"rendered":"https:\/\/international.nubank.com.br\/?p=24039"},"modified":"2026-04-08T14:27:36","modified_gmt":"2026-04-08T17:27:36","slug":"nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico","status":"publish","type":"post","link":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/","title":{"rendered":"Nubank lidera o ranking da Forbes no Brasil e no M\u00e9xico"},"content":{"rendered":"\n<p><strong>S\u00e3o Paulo, 8 de abril de 2026 \u2013<\/strong> Pelo oitavo ano consecutivo, o Nubank foi reconhecido na 1\u00aa posi\u00e7\u00e3o no Brasil e pelo quinto ano seguido no M\u00e9xico, no ranking Forbes&#8217; World&#8217;s Best Banks. A lista \u00e9 baseada em uma pesquisa independente conduzida pela empresa de pesquisa de mercado Statista com mais de 54.000 clientes banc\u00e1rios em 34 pa\u00edses. Este reconhecimento refor\u00e7a o compromisso do Nubank em construir a maior e mais amada franquia de banco de varejo globalmente.<br><br>No Brasil, o Nu se tornou a maior institui\u00e7\u00e3o financeira privada em n\u00famero de clientes, atingindo 113 milh\u00f5es com uma taxa de atividade de 86%. No M\u00e9xico, a empresa alcan\u00e7ou 14 milh\u00f5es de clientes, avan\u00e7ou no processo de licen\u00e7a banc\u00e1ria e apresentou cerca de metade de seus clientes ao seu primeiro cart\u00e3o de cr\u00e9dito por meio do Nu.<br><br>Al\u00e9m do World&#8217;s Best Banks da Forbes, o impacto do Nubank foi reconhecido por meio de diversas distin\u00e7\u00f5es globais, incluindo as 100 Empresas Mais Influentes da Time e as Empresas Mais Inovadoras da Fast Company.<br><br><strong>Sobre o ranking<\/strong><br>O ranking World&#8217;s Best Banks da Forbes \u00e9 determinado por meio de uma pesquisa independente com mais de 54.000 clientes banc\u00e1rios em 34 pa\u00edses, realizada em colabora\u00e7\u00e3o com a empresa de pesquisa de mercado Statista. Os participantes avaliam institui\u00e7\u00f5es com base em cinco crit\u00e9rios principais, reconhecendo a excel\u00eancia em servi\u00e7os banc\u00e1rios, fintechs e assessoria financeira.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nu conquista 1\u00ba lugar no Brasil pela oitava vez consecutiva e lidera no M\u00e9xico pelo quinto ano no ranking Forbes&#8217; World&#8217;s Best Banks<\/p>\n","protected":false},"author":249510384,"featured_media":20136,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[65],"tags":[271],"class_list":["post-24039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-companhia","tag-premios-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nubank lidera o ranking da Forbes no Brasil e no M\u00e9xico<\/title>\n<meta name=\"description\" content=\"Nu conquista 1\u00ba lugar no Brasil pela oitava vez consecutiva e lidera no M\u00e9xico pelo quinto ano no ranking Forbes&#039; World&#039;s Best Banks\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nubank lidera o ranking da Forbes no Brasil e no M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"Nu conquista 1\u00ba lugar no Brasil pela oitava vez consecutiva e lidera no M\u00e9xico pelo quinto ano no ranking Forbes&#039; World&#039;s Best Banks\" \/>\n<meta property=\"og:url\" content=\"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"Nu International\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-08T17:26:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T17:27:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/international.nubank.com.br\/wp-content\/uploads\/2025\/06\/image-1-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"654\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nuleonardostavale\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"nuleonardostavale\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/companhia\\\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/companhia\\\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\\\/\"},\"author\":{\"name\":\"nuleonardostavale\",\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/#\\\/schema\\\/person\\\/489f9ad4c63df4f21cc883de39f6249d\"},\"headline\":\"Nubank lidera o ranking da Forbes no Brasil e no M\u00e9xico\",\"datePublished\":\"2026-04-08T17:26:41+00:00\",\"dateModified\":\"2026-04-08T17:27:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/companhia\\\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\\\/\"},\"wordCount\":258,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/companhia\\\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/international.nubank.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/image-1-1-1.png\",\"keywords\":[\"Pr\u00eamios\"],\"articleSection\":[\"Companhia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/companhia\\\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/companhia\\\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\\\/\",\"url\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/companhia\\\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\\\/\",\"name\":\"Nubank lidera o ranking da Forbes no Brasil e no M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/companhia\\\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/companhia\\\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/international.nubank.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/image-1-1-1.png\",\"datePublished\":\"2026-04-08T17:26:41+00:00\",\"dateModified\":\"2026-04-08T17:27:36+00:00\",\"description\":\"Nu conquista 1\u00ba lugar no Brasil pela oitava vez consecutiva e lidera no M\u00e9xico pelo quinto ano no ranking Forbes' World's Best Banks\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/companhia\\\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/companhia\\\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/companhia\\\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/international.nubank.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/image-1-1-1.png\",\"contentUrl\":\"https:\\\/\\\/international.nubank.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/image-1-1-1.png\",\"width\":1080,\"height\":654},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/companhia\\\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nubank lidera o ranking da Forbes no Brasil e no M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/\",\"name\":\"Nu International\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/#organization\",\"name\":\"Nu International\",\"url\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/international.nubank.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/international.nubank.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Nu International\"},\"image\":{\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/#\\\/schema\\\/person\\\/489f9ad4c63df4f21cc883de39f6249d\",\"name\":\"nuleonardostavale\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2dbe45c5b04b17754136d0356df3700ca9c2cf3841efb1a8d65c5709eb471a66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2dbe45c5b04b17754136d0356df3700ca9c2cf3841efb1a8d65c5709eb471a66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2dbe45c5b04b17754136d0356df3700ca9c2cf3841efb1a8d65c5709eb471a66?s=96&d=mm&r=g\",\"caption\":\"nuleonardostavale\"},\"url\":\"https:\\\/\\\/international.nubank.com.br\\\/pt-br\\\/author\\\/nuleonardostavale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nubank lidera o ranking da Forbes no Brasil e no M\u00e9xico","description":"Nu conquista 1\u00ba lugar no Brasil pela oitava vez consecutiva e lidera no M\u00e9xico pelo quinto ano no ranking Forbes' World's Best Banks","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/","og_locale":"pt_BR","og_type":"article","og_title":"Nubank lidera o ranking da Forbes no Brasil e no M\u00e9xico","og_description":"Nu conquista 1\u00ba lugar no Brasil pela oitava vez consecutiva e lidera no M\u00e9xico pelo quinto ano no ranking Forbes' World's Best Banks","og_url":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/","og_site_name":"Nu International","article_published_time":"2026-04-08T17:26:41+00:00","article_modified_time":"2026-04-08T17:27:36+00:00","og_image":[{"width":1080,"height":654,"url":"https:\/\/international.nubank.com.br\/wp-content\/uploads\/2025\/06\/image-1-1-1.png","type":"image\/png"}],"author":"nuleonardostavale","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nuleonardostavale","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/#article","isPartOf":{"@id":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/"},"author":{"name":"nuleonardostavale","@id":"https:\/\/international.nubank.com.br\/pt-br\/#\/schema\/person\/489f9ad4c63df4f21cc883de39f6249d"},"headline":"Nubank lidera o ranking da Forbes no Brasil e no M\u00e9xico","datePublished":"2026-04-08T17:26:41+00:00","dateModified":"2026-04-08T17:27:36+00:00","mainEntityOfPage":{"@id":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/"},"wordCount":258,"commentCount":0,"publisher":{"@id":"https:\/\/international.nubank.com.br\/pt-br\/#organization"},"image":{"@id":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/international.nubank.com.br\/wp-content\/uploads\/2025\/06\/image-1-1-1.png","keywords":["Pr\u00eamios"],"articleSection":["Companhia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/","url":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/","name":"Nubank lidera o ranking da Forbes no Brasil e no M\u00e9xico","isPartOf":{"@id":"https:\/\/international.nubank.com.br\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/#primaryimage"},"image":{"@id":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/international.nubank.com.br\/wp-content\/uploads\/2025\/06\/image-1-1-1.png","datePublished":"2026-04-08T17:26:41+00:00","dateModified":"2026-04-08T17:27:36+00:00","description":"Nu conquista 1\u00ba lugar no Brasil pela oitava vez consecutiva e lidera no M\u00e9xico pelo quinto ano no ranking Forbes' World's Best Banks","breadcrumb":{"@id":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/#primaryimage","url":"https:\/\/international.nubank.com.br\/wp-content\/uploads\/2025\/06\/image-1-1-1.png","contentUrl":"https:\/\/international.nubank.com.br\/wp-content\/uploads\/2025\/06\/image-1-1-1.png","width":1080,"height":654},{"@type":"BreadcrumbList","@id":"https:\/\/international.nubank.com.br\/pt-br\/companhia\/nubank-lidera-o-ranking-da-forbes-no-brasil-e-no-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/international.nubank.com.br\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Nubank lidera o ranking da Forbes no Brasil e no M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/international.nubank.com.br\/pt-br\/#website","url":"https:\/\/international.nubank.com.br\/pt-br\/","name":"Nu International","description":"","publisher":{"@id":"https:\/\/international.nubank.com.br\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/international.nubank.com.br\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/international.nubank.com.br\/pt-br\/#organization","name":"Nu International","url":"https:\/\/international.nubank.com.br\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/international.nubank.com.br\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/international.nubank.com.br\/wp-content\/uploads\/2022\/08\/favicon.png","contentUrl":"https:\/\/international.nubank.com.br\/wp-content\/uploads\/2022\/08\/favicon.png","width":512,"height":512,"caption":"Nu International"},"image":{"@id":"https:\/\/international.nubank.com.br\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/international.nubank.com.br\/pt-br\/#\/schema\/person\/489f9ad4c63df4f21cc883de39f6249d","name":"nuleonardostavale","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2dbe45c5b04b17754136d0356df3700ca9c2cf3841efb1a8d65c5709eb471a66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2dbe45c5b04b17754136d0356df3700ca9c2cf3841efb1a8d65c5709eb471a66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2dbe45c5b04b17754136d0356df3700ca9c2cf3841efb1a8d65c5709eb471a66?s=96&d=mm&r=g","caption":"nuleonardostavale"},"url":"https:\/\/international.nubank.com.br\/pt-br\/author\/nuleonardostavale\/"}]}},"jetpack_featured_media_url":"https:\/\/international.nubank.com.br\/wp-content\/uploads\/2025\/06\/image-1-1-1.png","jetpack_shortlink":"https:\/\/wp.me\/peaOGT-6fJ","_links":{"self":[{"href":"https:\/\/international.nubank.com.br\/pt-br\/wp-json\/wp\/v2\/posts\/24039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/international.nubank.com.br\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/international.nubank.com.br\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/international.nubank.com.br\/pt-br\/wp-json\/wp\/v2\/users\/249510384"}],"replies":[{"embeddable":true,"href":"https:\/\/international.nubank.com.br\/pt-br\/wp-json\/wp\/v2\/comments?post=24039"}],"version-history":[{"count":2,"href":"https:\/\/international.nubank.com.br\/pt-br\/wp-json\/wp\/v2\/posts\/24039\/revisions"}],"predecessor-version":[{"id":24046,"href":"https:\/\/international.nubank.com.br\/pt-br\/wp-json\/wp\/v2\/posts\/24039\/revisions\/24046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/international.nubank.com.br\/pt-br\/wp-json\/wp\/v2\/media\/20136"}],"wp:attachment":[{"href":"https:\/\/international.nubank.com.br\/pt-br\/wp-json\/wp\/v2\/media?parent=24039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/international.nubank.com.br\/pt-br\/wp-json\/wp\/v2\/categories?post=24039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/international.nubank.com.br\/pt-br\/wp-json\/wp\/v2\/tags?post=24039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}